{"id":2770,"date":"2021-04-28T09:14:39","date_gmt":"2021-04-28T09:14:39","guid":{"rendered":"http:\/\/test-ikf.online\/?page_id=2770"},"modified":"2021-04-28T09:15:07","modified_gmt":"2021-04-28T09:15:07","slug":"2001-arbeitsgruppe-wehrpolitische-ausbildung","status":"publish","type":"page","link":"https:\/\/ikf.ac.at\/en\/schwerpunkte\/sicherheit\/rechtsstaat\/2001-arbeitsgruppe-wehrpolitische-ausbildung","title":{"rendered":"2001: Arbeitsgruppe Wehrpolitische Ausbildung"},"content":{"rendered":"<div class=\"wp-block-atomic-blocks-ab-container alignfull ab-block-container\"><div class=\"ab-container-inside\"><div class=\"ab-container-content\"><div id=\"pl-gb2770-6a97a6a92a1a6\"  class=\"panel-layout\" ><div id=\"pg-gb2770-6a97a6a92a1a6-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb2770-6a97a6a92a1a6-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb2770-6a97a6a92a1a6-0-0-0\" class=\"so-panel widget widget_media_image panel-first-child panel-last-child\" data-index=\"0\" ><img loading=\"lazy\" decoding=\"async\" width=\"2554\" height=\"10\" src=\"https:\/\/ikf.ac.at\/wp-content\/uploads\/2021\/01\/linie_IKF.jpg\" class=\"image wp-image-754  attachment-full size-full\" alt=\"\" style=\"max-width: 100%; height: auto;\" srcset=\"https:\/\/ikf.ac.at\/wp-content\/uploads\/2021\/01\/linie_IKF.jpg 2554w, https:\/\/ikf.ac.at\/wp-content\/uploads\/2021\/01\/linie_IKF-300x1.jpg 300w, https:\/\/ikf.ac.at\/wp-content\/uploads\/2021\/01\/linie_IKF-1024x4.jpg 1024w, https:\/\/ikf.ac.at\/wp-content\/uploads\/2021\/01\/linie_IKF-768x3.jpg 768w, https:\/\/ikf.ac.at\/wp-content\/uploads\/2021\/01\/linie_IKF-1536x6.jpg 1536w, https:\/\/ikf.ac.at\/wp-content\/uploads\/2021\/01\/linie_IKF-2048x8.jpg 2048w\" sizes=\"auto, (max-width: 2554px) 100vw, 2554px\" \/><\/div><\/div><\/div><\/div>\n\n\n<div style=\"color:#ddd\" class=\"wp-block-genesis-blocks-gb-spacer gb-block-spacer gb-divider-solid gb-divider-size-1\"><hr style=\"height:30px\"\/><\/div>\n\n\n<div id=\"pl-gb2770-6a97a6a93e154\"  class=\"panel-layout\" ><div id=\"pg-gb2770-6a97a6a93e154-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb2770-6a97a6a93e154-0-0\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><div id=\"pgc-gb2770-6a97a6a93e154-0-1\"  class=\"panel-grid-cell\" ><div id=\"panel-gb2770-6a97a6a93e154-0-1-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<table style=\"height: 220px;width: 100%;border-collapse: collapse\" border=\"1\" cellpadding=\"2\">\n<tbody>\n<tr style=\"height: 24px\">\n<td style=\"width: 25.7099%;height: 24px\">Projektleitung und Durchf\u00fchrung:<\/td>\n<td style=\"width: 74.2901%;height: 24px\" colspan=\"2\">Dr. Wolfgang Knopf<br \/>\nDr. Birgitt Haller<\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"width: 25.7099%;height: 24px\">\n<hr \/>\n<\/td>\n<td style=\"width: 59.4085%;height: 24px\">\n<hr \/>\n<\/td>\n<td style=\"width: 14.8816%;height: 24px\"><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"width: 25.7099%;height: 24px\">Kooperation mit:<\/td>\n<td style=\"width: 74.2901%;height: 24px\" colspan=\"2\">Institut f\u00fcr Interdisziplin\u00e4re Forschung und Fortbildung (IFF), Politische Bildung<\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"width: 25.7099%;height: 24px\">\n<hr \/>\n<\/td>\n<td style=\"width: 59.4085%;height: 24px\">\n<hr \/>\n<\/td>\n<td style=\"width: 14.8816%;height: 24px\"><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"width: 25.7099%;height: 24px\">Funded by:<\/td>\n<td style=\"width: 74.2901%;height: 24px\" colspan=\"2\">Bundesministerium f\u00fcr Landesverteidigung<\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"width: 25.7099%;height: 24px\">\n<hr \/>\n<\/td>\n<td style=\"width: 59.4085%;height: 24px\">\n<hr \/>\n<\/td>\n<td style=\"width: 14.8816%;height: 24px\"><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"width: 25.7099%;height: 24px\">Completed in:<\/td>\n<td style=\"height: 24px;width: 74.2901%\" colspan=\"2\">Dezember 2001<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div>\n\n\n<div style=\"color:#404168\" class=\"wp-block-genesis-blocks-gb-spacer gb-block-spacer gb-divider-solid gb-spacer-divider gb-divider-size-1\"><hr style=\"height:3px\"\/><\/div>\n\n\n\n<div style=\"color:#404168\" class=\"wp-block-genesis-blocks-gb-spacer gb-block-spacer gb-divider-solid gb-divider-size-1\"><hr style=\"height:10px\"\/><\/div>\n\n\n<div id=\"pl-gb2770-6a97a6a93e738\"  class=\"panel-layout\" ><div id=\"pg-gb2770-6a97a6a93e738-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb2770-6a97a6a93e738-0-0\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><div id=\"pgc-gb2770-6a97a6a93e738-0-1\"  class=\"panel-grid-cell panel-grid-cell-mobile-last\" ><div id=\"panel-gb2770-6a97a6a93e738-0-1-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" >\t\t\t<div class=\"textwidget\"><p align=\"justify\">Der 1996 begonnene Ausbildungslehrgang &#8220;Politische Bildung f\u00fcr Lehroffiziere im Rahmen der Wehrpolitischen Ausbildung&#8221;, an dem die drei Akademien sowie mehrere Waffen- und Fachschulen teilnahmen, wurde mit Jahresende 2001 abgeschlossen.<\/p>\n<p align=\"justify\">Der urspr\u00fcngliche Auftrag an das IFF \/ Programmbereich &#8220;Politische Bildung&#8221; (Wolfgang Knopf), das dabei mit dem IKF zusammenarbeitete, sah vor, dass ein Kursangebot f\u00fcr Lehroffiziere unter Einbeziehung eines von der Deutschen Bundeswehr konzipierten Planspiels entwickelt werden sollte. Auf Grund von verschiedenen Schwachstellen dieses Planspiels, das im Rahmen eines Workshops durchgef\u00fchrt wurde, beschlossen die Workshopteilnehmer gemeinsam mit dem Leitungsteam, in der wehrpolitischen Ausbildung f\u00fcr Lehroffiziere nicht weiter damit zu arbeiten. Das Projektstaff schlug daher als Alternative zur Fortsetzung des Projekts ein aus Modulen bestehendes Modell vor.<\/p>\n<p align=\"justify\"><em>Modul 1<\/em>\u00a0sollte als p\u00e4dagogisch-didaktischer Veranstaltungsblock stattfinden. Als Teilnehmer wurde die bestehende bzw. eventuell um einige Personen erweiterte &#8220;Kerngruppe&#8221; vorgesehen, die sich beim Workshop konstituiert hatte. Anhand eines vorgegebenen Themas \u2013 n\u00e4mlich &#8220;Vorurteil&#8221; \u2013 sollte exemplarisch eine Palette von affektiven Zugangsweisen vorgestellt und durchgearbeitet werden. Dieses Thema wurde ausgew\u00e4hlt, da es f\u00fcr die Politische Bildung zentral ist und sich aufgrund seiner emotionalen Vielschichtigkeit und seines f\u00e4cher\u00fcbergreifenden Charakters gut eignet, um ein breites Spektrum von Methoden zu erarbeiten. Im Anschluss daran wurde als\u00a0<em>Modul 2<\/em>\u00a0ein politikwissenschaftlicher Block vorgesehen, bei dem Elemente aus Modul 1 ein- und umgesetzt werden sollten. Schlie\u00dflich sollten alle Teilnehmer an ihren Akademien bzw. Schulen\u00a0<em>Projects<\/em>\u00a0zu Inhalten der Politischen Bildung durchf\u00fchren, wobei das Projektstaff Unterst\u00fctzung bei deren Planung, Durchf\u00fchrung und Reflexion leisten sollte.<\/p>\n<p align=\"justify\">Mit dem\u00a0<em>Modul 3<\/em>\u00a0wurde zum einen die M\u00f6glichkeit der Reflexion des Erarbeiteten und zum anderen des Transfers in den jeweiligen Unterrichtsbetrieb an den Akademien und Schulen angeboten.<\/p>\n<p align=\"justify\">Nach diesem Modell erfolgten j\u00e4hrlich vier Treffen: zwei Arbeitsgruppentreffen, die der Koordinierung und dem Informationsaustausch dienten, sowie je ein methodisch-didaktischer und ein politikwissenschaftlicher Workshop. Durch die Teilnahme an diesem Ausbildungslehrgang sollten die Absolventen bef\u00e4higt werden, ihren Unterricht im Bereich der (Wehr-)Politischen Bildung unter Einbeziehung politikwissenschaftlicher Grundlagen und aktueller wehrpolitischer Anl\u00e4sse didaktisch zeitgem\u00e4\u00df zu vermitteln.<\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-gb2770-6a97a6a93e738-0-2\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><\/div><\/div>\n\n\n<div style=\"color:#333\" class=\"wp-block-genesis-blocks-gb-spacer gb-block-spacer gb-divider-solid gb-spacer-divider gb-divider-size-1\"><hr style=\"height:100px\"\/><\/div>\n<\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":959,"menu_order":31,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2770","page","type-page","status-publish","hentry","post"],"featured_image_src":null,"featured_image_src_square":null,"_links":{"self":[{"href":"https:\/\/ikf.ac.at\/en\/wp-json\/wp\/v2\/pages\/2770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ikf.ac.at\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ikf.ac.at\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ikf.ac.at\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ikf.ac.at\/en\/wp-json\/wp\/v2\/comments?post=2770"}],"version-history":[{"count":1,"href":"https:\/\/ikf.ac.at\/en\/wp-json\/wp\/v2\/pages\/2770\/revisions"}],"predecessor-version":[{"id":2771,"href":"https:\/\/ikf.ac.at\/en\/wp-json\/wp\/v2\/pages\/2770\/revisions\/2771"}],"up":[{"embeddable":true,"href":"https:\/\/ikf.ac.at\/en\/wp-json\/wp\/v2\/pages\/959"}],"wp:attachment":[{"href":"https:\/\/ikf.ac.at\/en\/wp-json\/wp\/v2\/media?parent=2770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}