{"id":2488,"date":"2021-04-08T10:15:30","date_gmt":"2021-04-08T10:15:30","guid":{"rendered":"http:\/\/test-ikf.online\/?page_id=2488"},"modified":"2021-04-08T10:16:16","modified_gmt":"2021-04-08T10:16:16","slug":"2003-verschuldung-von-migrantinnen-in-wien","status":"publish","type":"page","link":"https:\/\/ikf.ac.at\/en\/schwerpunkte\/cleavages\/integration-migration\/2003-verschuldung-von-migrantinnen-in-wien","title":{"rendered":"2003: Verschuldung von MigrantInnen in Wien. Ursachen, Ausma\u00df und Folgen"},"content":{"rendered":"<div class=\"wp-block-atomic-blocks-ab-container alignfull ab-block-container\"><div class=\"ab-container-inside\"><div class=\"ab-container-content\"><div id=\"pl-gb2488-6a97a9fc4195c\"  class=\"panel-layout\" ><div id=\"pg-gb2488-6a97a9fc4195c-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb2488-6a97a9fc4195c-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb2488-6a97a9fc4195c-0-0-0\" class=\"so-panel widget widget_media_image panel-first-child panel-last-child\" data-index=\"0\" ><img loading=\"lazy\" decoding=\"async\" width=\"2554\" height=\"10\" src=\"https:\/\/ikf.ac.at\/wp-content\/uploads\/2021\/01\/linie_IKF.jpg\" class=\"image wp-image-754  attachment-full size-full\" alt=\"\" style=\"max-width: 100%; height: auto;\" srcset=\"https:\/\/ikf.ac.at\/wp-content\/uploads\/2021\/01\/linie_IKF.jpg 2554w, https:\/\/ikf.ac.at\/wp-content\/uploads\/2021\/01\/linie_IKF-300x1.jpg 300w, https:\/\/ikf.ac.at\/wp-content\/uploads\/2021\/01\/linie_IKF-1024x4.jpg 1024w, https:\/\/ikf.ac.at\/wp-content\/uploads\/2021\/01\/linie_IKF-768x3.jpg 768w, https:\/\/ikf.ac.at\/wp-content\/uploads\/2021\/01\/linie_IKF-1536x6.jpg 1536w, https:\/\/ikf.ac.at\/wp-content\/uploads\/2021\/01\/linie_IKF-2048x8.jpg 2048w\" sizes=\"auto, (max-width: 2554px) 100vw, 2554px\" \/><\/div><\/div><\/div><\/div>\n\n\n<div style=\"color:#ddd\" class=\"wp-block-genesis-blocks-gb-spacer gb-block-spacer gb-divider-solid gb-divider-size-1\"><hr style=\"height:30px\"\/><\/div>\n\n\n<div id=\"pl-gb2488-6a97a9fc59168\"  class=\"panel-layout\" ><div id=\"pg-gb2488-6a97a9fc59168-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb2488-6a97a9fc59168-0-0\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><div id=\"pgc-gb2488-6a97a9fc59168-0-1\"  class=\"panel-grid-cell\" ><div id=\"panel-gb2488-6a97a9fc59168-0-1-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<table style=\"height: 100px;width: 100%;border-collapse: collapse\" border=\"1\" cellpadding=\"2\">\n<tbody>\n<tr style=\"height: 24px\">\n<td style=\"width: 15.8421%;height: 24px\">Project management:<\/td>\n<td style=\"width: 84.1578%;height: 24px\" colspan=\"2\">Univ.-Prof. Dr. Anton Pelinka<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 15.8421%\">\n<hr \/>\n<\/td>\n<td style=\"width: 32.4567%\">\n<hr \/>\n<\/td>\n<td style=\"width: 51.7011%;height: 24px\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 15.8421%\">Project team:<\/td>\n<td style=\"width: 84.1578%\" colspan=\"2\">Dr.<sup>in<\/sup> Birgitt Haller<br \/>\nMMag.<sup>a<\/sup> Karin St\u00f6gner<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 15.8421%\">\n<hr \/>\n<\/td>\n<td style=\"width: 32.4567%\">\n<hr \/>\n<\/td>\n<td style=\"width: 51.7011%\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 15.8421%\">Funded by:<\/td>\n<td style=\"width: 84.1578%\" colspan=\"2\">Wiener Integrationsfonds<br \/>\nKammer f\u00fcr Arbeiter und Angestellte Wien<br \/>\nMA 57<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 15.8421%\">\n<hr \/>\n<\/td>\n<td style=\"width: 32.4567%\">\n<hr \/>\n<\/td>\n<td style=\"width: 51.7011%;height: 24px\"><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"width: 15.8421%;height: 24px\">Completed in:<\/td>\n<td style=\"height: 24px;width: 84.1578%\" colspan=\"2\">September 2003<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div>\n\n\n<div style=\"color:#404168\" class=\"wp-block-genesis-blocks-gb-spacer gb-block-spacer gb-divider-solid gb-spacer-divider gb-divider-size-1\"><hr style=\"height:3px\"\/><\/div>\n\n\n\n<div style=\"color:#404168\" class=\"wp-block-genesis-blocks-gb-spacer gb-block-spacer gb-divider-solid gb-divider-size-1\"><hr style=\"height:10px\"\/><\/div>\n\n\n<div id=\"pl-gb2488-6a97a9fc59740\"  class=\"panel-layout\" ><div id=\"pg-gb2488-6a97a9fc59740-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb2488-6a97a9fc59740-0-0\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><div id=\"pgc-gb2488-6a97a9fc59740-0-1\"  class=\"panel-grid-cell panel-grid-cell-mobile-last\" ><div id=\"panel-gb2488-6a97a9fc59740-0-1-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" >\t\t\t<div class=\"textwidget\"><p align=\"justify\">Mit der vorliegenden Untersuchung wurde versucht die Ver- bzw. \u00dcberschuldungssituation von MigrantInnen in Wien zu erfassen, wobei sowohl quantitative als auch qualitative Erhebungen durchgef\u00fchrt wurden. Im Rahmen der\u00a0<em>quantitativen Erhebung\u00a0<\/em>erfolgte eine Auswertung der (anonymisierten) Datenbankeneintragungen aus dem zweiten Halbjahr 2002 bei der Schuldnerberatung der Stadt Wien und der KWH. Dabei konnten einige Unterschiede zwischen migrierten und &#8220;\u00f6sterreichischen&#8221; KlientInnen herausgearbeitet werden. Ein Manko besteht darin, dass aufgrund der Struktur der Datenbanken in \u00d6sterreich geborene eingeb\u00fcrgerte MigrantInnen, also Angeh\u00f6rige der zweiten Generation, nicht erfasst werden konnten. Als MigrantInnen wurden hier Personen definiert, die entweder (unabh\u00e4ngig von ihrem Geburtsort) \u00fcber eine fremde Staatsb\u00fcrgerschaft verf\u00fcgen oder die im Ausland geboren sind (unabh\u00e4ngig von ihrer Staatsb\u00fcrgerschaft). Erg\u00e4nzend zu den Datenbankauswertungen erfolgte zwei Wochen lang eine Fragebogenerhebung bei migrierten KlientInnen der beiden Schuldnerberatungseinrichtungen. Damit konnten genauere Informationen \u00fcber ihre Verschuldungssituation bei 102 Personen mit nicht-deutscher Muttersprache (also auch bei Angeh\u00f6rigen der 2. Generation) eingeholt werden. Der\u00a0<em>qualitative Zugang<\/em>\u00a0zum Untersuchungsthema erfolgte durch Interviews mit verschuldeten MigrantInnen (M\u00e4nner, Frauen und Jugendliche) sowie mit VertreterInnen der Gl\u00e4ubigerseite und mit Mitarbeitern der beiden Schuldnerberatungsstellen.<\/p>\n<p align=\"justify\">Von den KlientInnen der beiden Wiener Schuldenberatungsstellen sind rund ein F\u00fcnftel Ausl\u00e4nderInnen\/im Ausland geborene KlientInnen und rund die H\u00e4lfte Personen mit nicht-deutscher Muttersprache, also MigrantInnen. Das hei\u00dft, dass Ausl\u00e4nderInnen und im Ausland Geborene in Relation zu ihrem Bev\u00f6lkerungsanteil unter den KlientInnen ann\u00e4hernd ad\u00e4quat repr\u00e4sentiert sind, in \u00d6sterreich geborene eingeb\u00fcrgerte MigrantInnen sind aber stark \u00fcberrepr\u00e4sentiert.<\/p>\n<p align=\"justify\">Einige Merkmale der\u00a0<em>migrierten KlientInnen<\/em>\u00a0der Beratungsstellen fallen auf: Die Altersgruppe der 41- bis 50-J\u00e4hrigen ist bei ihnen deutlich st\u00e4rker vertreten als bei den \u00d6sterreicherInnen, und unter den Migrantinnen finden sich \u00fcberproportional viele geschiedene Frauen (und Alleinerzieherinnen). Das h\u00e4ngt mit der\u00a0<em>Arbeits- und Einkommenssituation<\/em>\u00a0von MigrantInnen zusammen. Einerseits sind \u00e4ltere ArbeitnehmerInnen st\u00e4rker armutsgef\u00e4hrdet, weil sie in erh\u00f6htem Ausma\u00df von Arbeitslosigkeit betroffen sind. Zum anderen haben gerade Frauen sehr niedrige Einkommen, die im Falle einer Scheidung &#8211; und insbesondere dann, wenn Kreditbelastungen etwa durch B\u00fcrgschaften bestehen &#8211; kaum f\u00fcr die Existenzsicherung ausreichen.<\/p>\n<p align=\"justify\">Die beiden\u00a0<em>Verschuldungsursachen<\/em>\u00a0Arbeitslosigkeit und zu geringes Einkommen zusammengenommen standen hinter einem Viertel aller \u00dcberschuldungen. Au\u00dferdem ergab die Datenbankauswertung, dass Wohnen von jedem\/jeder achten MigrantIn, aber nur von jedem\/jeder zw\u00f6lften \u00d6sterreicherIn genannt wurde. Es ist also bei MigrantInnen vor allem die Befriedigung von\u00a0<em>Grundbed\u00fcrfnissen<\/em>\u00a0schwierig und oft mit dem Schritt in die Armutsfalle verbunden. Im \u00dcbrigen verschulden sich deutlich weniger MigrantInnen als \u00d6sterreicherInnen durch eine T\u00e4tigkeit als Selbstst\u00e4ndige.<\/p>\n<p align=\"justify\">Auffallend ist, dass vor allem Frauen in Folge einer\u00a0<em>Scheidung<\/em>\u00a0oder Trennung \u00fcberschuldet sind. Das h\u00e4ngt u.a. damit zusammen, dass Migrantinnen wesentlich h\u00e4ufiger als \u00d6sterreicherinnen\u00a0<em>B\u00fcrgschaften<\/em>\u00a0f\u00fcr den Partner \u00fcbernommen haben (vor allem in Zusammenhang mit dessen selbstst\u00e4ndiger T\u00e4tigkeit) und als Zahlerin herangezogen werden. Hier spielt nicht nur der Druck von Banken zur B\u00fcrgschafts\u00fcbernahme eine Rolle (der laut Aussagen von BankenvertreterInnen in den letzten Jahren schw\u00e4cher geworden ist), sondern auch, dass viele Migrantinnen sehr schlecht oder kaum Deutsch sprechen und verstehen und in vielen F\u00e4llen nicht wissen, wozu sie sich verpflichten, bzw. von ihren Partnern zur Unterschrift gezwungen werden.<\/p>\n<p align=\"justify\">\u00dcberraschend war, dass MigrantInnen unter den AntragstellerInnen auf einen\u00a0<em>Privatkonkurs<\/em>\u00a0sehr stark vertreten waren. Dieses Ergebnis der Datenbankauswertung korrespondiert mit der Einsch\u00e4tzung eines Gespr\u00e4chspartners vom Kreditschutzverband von 1870. Da MigrantInnen grunds\u00e4tzlich aufgrund ihrer schlechteren Arbeits- und Einkommensverh\u00e4ltnisse schlechtere Chancen auf einen Privatkonkurs haben, d\u00fcrfte die Einsch\u00e4tzung eines Schuldnerberaters zutreffen, dass gerade MigrantInnen besonders stark motiviert sind, einen Privatkonkurs durchzuziehen.<\/p>\n<p align=\"justify\">Es konnten\u00a0<em>23 Interviews<\/em>\u00a0mit verschuldeten M\u00e4nnern, Frauen und Jugendlichen durchgef\u00fchrt werden. Ein Manko der Untersuchung besteht darin, dass keine erwachsenen Gespr\u00e4chspartnerInnen aus dem ehemaligen Jugoslawien gefunden werden konnten. W\u00e4hrend es zun\u00e4chst generell sehr schwierig war, InterviewpartnerInnen zu finden, gelang uns dies \u00fcber die Vermittlung von verschiedenen Beratungseinrichtungen schlie\u00dflich doch. Diese Einrichtungen arbeiten aber in erster Linie mit T\u00fcrkInnen bzw. scheinen T\u00fcrkInnen \u00fcber engere Netzwerke zu verf\u00fcgen als Personen aus dem fr\u00fcheren Jugoslawien, so dass letztlich T\u00fcrkInnen leichter zu einem Gespr\u00e4ch motivierbar waren. Die Schwierigkeiten beim Zugang zu InterviewpartnerInnen verdeutlichen, wie sehr Ver-\/\u00dcberschuldung ein Tabuthema ist. Unseren InterviewpartnerInnen ging es nicht nur psychisch sehr schlecht, sie sch\u00e4mten sich auch ihrer Situation. Die meisten waren nur aufgrund des Vertrauensverh\u00e4ltnisses zu ihren BetreuerInnen, die ihnen die Wichtigkeit des Forschungsprojektes nahe brachten, zu einem Gespr\u00e4ch bereit.<\/p>\n<p align=\"justify\">Aus unserer Sicht liegen die Gr\u00fcnde f\u00fcr das\u00a0<em>\u00fcberproportionale Verschuldungsrisiko<\/em> von MigrantInnen in erster Linie in deren Lebenssituation. Verglichen mit den \u00d6sterreicherInnen und EU-Ausl\u00e4nderInnen sind ihre Einkommen niedriger und sie sind mit h\u00f6herer Arbeitslosigkeit konfrontiert. Ein gro\u00dfes Problem liegt darin, dass auch die zweite Generation am Arbeitsmarkt \u00fcber keine deutlich besseren Chancen verf\u00fcgt, viele Jugendliche haben keine weiterf\u00fchrende Schulbildung und auch sie arbeiten vornehmlich in Niedriglohnbranchen. Dazu kommt bei den meisten MigrantInnen die Notwendigkeit von hohen finanziellen Aufwendungen f\u00fcr das Grundbed\u00fcrfnis Wohnen. Eine nachhaltige Reduzierung des Verschuldungsrisikos von MigrantInnen m\u00fcsste bei diesen gesellschaftlichen Bereichen ansetzen.<\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-gb2488-6a97a9fc59740-0-2\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><\/div><\/div>\n\n\n<div style=\"color:#333\" class=\"wp-block-genesis-blocks-gb-spacer gb-block-spacer gb-divider-solid gb-spacer-divider gb-divider-size-1\"><hr style=\"height:100px\"\/><\/div>\n<\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":457,"menu_order":35,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2488","page","type-page","status-publish","hentry","post"],"featured_image_src":null,"featured_image_src_square":null,"_links":{"self":[{"href":"https:\/\/ikf.ac.at\/en\/wp-json\/wp\/v2\/pages\/2488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ikf.ac.at\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ikf.ac.at\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ikf.ac.at\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ikf.ac.at\/en\/wp-json\/wp\/v2\/comments?post=2488"}],"version-history":[{"count":3,"href":"https:\/\/ikf.ac.at\/en\/wp-json\/wp\/v2\/pages\/2488\/revisions"}],"predecessor-version":[{"id":2491,"href":"https:\/\/ikf.ac.at\/en\/wp-json\/wp\/v2\/pages\/2488\/revisions\/2491"}],"up":[{"embeddable":true,"href":"https:\/\/ikf.ac.at\/en\/wp-json\/wp\/v2\/pages\/457"}],"wp:attachment":[{"href":"https:\/\/ikf.ac.at\/en\/wp-json\/wp\/v2\/media?parent=2488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}